{"id":38861,"date":"2024-05-13T21:33:13","date_gmt":"2024-05-13T14:33:13","guid":{"rendered":"https:\/\/www.learn.co.th\/?p=38861"},"modified":"2024-05-13T21:33:13","modified_gmt":"2024-05-13T14:33:13","slug":"4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84","status":"publish","type":"post","link":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/","title":{"rendered":"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07"},"content":{"rendered":"<p>\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d \u0e42\u0e08\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e22\u0e38\u0e04 Talent War \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e37\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e08\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e32\u0e40\u0e25\u0e19\u0e15\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e17\u0e32\u0e40\u0e25\u0e19\u0e15\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>4 <a href=\"https:\/\/www.learn.co.th\/?utm_source=facebook-lc&amp;utm_medium=lc&amp;utm_campaign=facebook\">\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04<\/a> \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e17\u0e35\u0e48 <a href=\"https:\/\/www.youtube.com\/watch?v=phnN-QTGe_U\">HR<\/a> \u0e04\u0e27\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-38865 size-medium\" src=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-300x300.jpg\" alt=\"\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-300x300.jpg 300w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-1024x1024.jpg 1024w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-150x150.jpg 150w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-768x768.jpg 768w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-1536x1536.jpg 1536w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-350x350.jpg 350w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0-348x348.jpg 348w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.2_2_0.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ol>\n<li><strong>Hybrid Work Models and Flexibility<\/strong><\/li>\n<\/ol>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e1f\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e27\u0e25\u0e32\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e01\u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e42\u0e1f\u0e01\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49 \u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e31\u0e01\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e31\u0e19\u0e1a\u0e48\u0e2d\u0e22 \u0e46 \u0e04\u0e37\u0e2d \u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e15\u0e4a\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a Hot Seat \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e35\u0e48\u0e40\u0e22\u0e2d\u0e30\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-38867 size-medium\" src=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-300x300.jpg\" alt=\"\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-300x300.jpg 300w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-1024x1024.jpg 1024w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-150x150.jpg 150w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-768x768.jpg 768w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-1536x1536.jpg 1536w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-350x350.jpg 350w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0-348x348.jpg 348w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.3_2_0.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ol start=\"2\">\n<li><strong>DEI&amp;B (Diversity, Equity, Inclusion and Belonging)<\/strong><\/li>\n<\/ol>\n<p>DEI&amp;B \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e04\u0e37\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e17\u0e48\u0e32\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e08\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e21\u0e35\u0e15\u0e31\u0e27\u0e15\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 HR \u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e01\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e01\u0e23\u0e30\u0e41\u0e2a DEI&amp;B \u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e17\u0e48\u0e32\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e16\u0e39\u0e01\u0e01\u0e35\u0e14\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e1d\u0e31\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-38871 size-medium\" src=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-300x300.jpg\" alt=\"Wellbeing\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-300x300.jpg 300w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-1024x1024.jpg 1024w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-150x150.jpg 150w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-768x768.jpg 768w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-1536x1536.jpg 1536w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-350x350.jpg 350w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0-348x348.jpg 348w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2_0.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ol start=\"3\">\n<li><strong>Health and Wellbeing<\/strong><\/li>\n<\/ol>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1a\u0e2a\u0e34\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e21\u0e35 \u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 HR \u0e04\u0e27\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e21\u0e35\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e34\u0e15\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e27\u0e25\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e27\u0e31\u0e19\u0e25\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e34\u0e15 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e31\u0e19\u0e25\u0e32\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 LGBTQ+ \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-38869 size-medium\" src=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-300x300.jpg\" alt=\"\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-300x300.jpg 300w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-1024x1024.jpg 1024w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-150x150.jpg 150w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-768x768.jpg 768w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-1536x1536.jpg 1536w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-350x350.jpg 350w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0-348x348.jpg 348w, https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.5_1_0.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ol start=\"4\">\n<li><strong>Reward and Recognition<\/strong><\/li>\n<\/ol>\n<p>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e21\u0e35\u0e15\u0e31\u0e27\u0e15\u0e19 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e01\u0e1e\u0e31\u0e19\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e17\u0e33\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07 Wellbeing, Benefit \u0e2b\u0e23\u0e37\u0e2d Compensation \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e14\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22 Reward \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e27\u0e31\u0e14\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01 Result \u0e2a\u0e48\u0e27\u0e19 Recognition \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e27\u0e31\u0e14\u0e08\u0e32\u0e01 Effort \u0e2b\u0e23\u0e37\u0e2d Contribute \u0e17\u0e35\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d \u0e42\u0e08\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e22\u0e38\u0e04 Talent War \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e37\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e08\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e32\u0e40\u0e25\u0e19\u0e15\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e17\u0e32\u0e40\u0e25\u0e19\u0e15\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 &nbsp; 4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e17\u0e35\u0e48 HR [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":38862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[273],"class_list":["post-38861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-273"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07<\/title>\n<meta name=\"description\" content=\"\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\" \/>\n<meta property=\"og:description\" content=\"\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/\" \/>\n<meta property=\"og:site_name\" content=\"LEARN Corporation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/LEARNCorporation\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-13T14:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.1_2_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/person\\\/244e89517660d41e1603149fe153956f\"},\"headline\":\"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\",\"datePublished\":\"2024-05-13T14:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/\"},\"wordCount\":47,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2.1_2_0.jpg\",\"keywords\":[\"\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\"],\"articleSection\":[\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/\",\"name\":\"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2.1_2_0.jpg\",\"datePublished\":\"2024-05-13T14:33:13+00:00\",\"description\":\"\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2.1_2_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2.1_2_0.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/articles\\\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/\",\"name\":\"LEARN Corporation\",\"description\":\"Lifelong Learning EdTech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#organization\"},\"alternateName\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#organization\",\"name\":\"LEARN Corporation\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/learn-corporation-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/learn-corporation-cover.jpg\",\"width\":2064,\"height\":1164,\"caption\":\"LEARN Corporation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/LEARNCorporation\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/person\\\/244e89517660d41e1603149fe153956f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07","description":"\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/","og_locale":"en_US","og_type":"article","og_title":"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07","og_description":"\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d","og_url":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/","og_site_name":"LEARN Corporation","article_publisher":"https:\/\/web.facebook.com\/LEARNCorporation\/","article_published_time":"2024-05-13T14:33:13+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.1_2_0.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#article","isPartOf":{"@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/"},"author":{"name":"admin","@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/person\/244e89517660d41e1603149fe153956f"},"headline":"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07","datePublished":"2024-05-13T14:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/"},"wordCount":47,"commentCount":0,"publisher":{"@id":"https:\/\/www.learn.co.th\/en\/#organization"},"image":{"@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#primaryimage"},"thumbnailUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.1_2_0.jpg","keywords":["\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19"],"articleSection":["\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/","url":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/","name":"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07","isPartOf":{"@id":"https:\/\/www.learn.co.th\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#primaryimage"},"image":{"@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#primaryimage"},"thumbnailUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.1_2_0.jpg","datePublished":"2024-05-13T14:33:13+00:00","description":"\u0e14\u0e49\u0e27\u0e22\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e38\u0e40\u0e14\u0e37\u0e2d\u0e14 HR \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e41\u0e04\u0e48\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19\u201d","breadcrumb":{"@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#primaryimage","url":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.1_2_0.jpg","contentUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2024\/05\/2.1_2_0.jpg","width":1920,"height":1920,"caption":"\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19"},{"@type":"BreadcrumbList","@id":"https:\/\/www.learn.co.th\/en\/articles\/4-%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%84%e0%b8%99-%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%84\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.learn.co.th\/en\/"},{"@type":"ListItem","position":2,"name":"4 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e43\u0e08\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e22\u0e48\u0e07\u0e0a\u0e34\u0e07\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.learn.co.th\/en\/#website","url":"https:\/\/www.learn.co.th\/en\/","name":"LEARN Corporation","description":"Lifelong Learning EdTech","publisher":{"@id":"https:\/\/www.learn.co.th\/en\/#organization"},"alternateName":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.learn.co.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.learn.co.th\/en\/#organization","name":"LEARN Corporation","url":"https:\/\/www.learn.co.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2026\/09\/learn-corporation-cover.jpg","contentUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2026\/09\/learn-corporation-cover.jpg","width":2064,"height":1164,"caption":"LEARN Corporation"},"image":{"@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/LEARNCorporation\/"]},{"@type":"Person","@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/person\/244e89517660d41e1603149fe153956f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts\/38861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/comments?post=38861"}],"version-history":[{"count":8,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts\/38861\/revisions"}],"predecessor-version":[{"id":38880,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts\/38861\/revisions\/38880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/media\/38862"}],"wp:attachment":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/media?parent=38861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/categories?post=38861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/tags?post=38861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}