{"id":38364,"date":"2023-12-20T14:21:48","date_gmt":"2023-12-20T07:21:48","guid":{"rendered":"https:\/\/www.learn.co.th\/?p=38364"},"modified":"2023-12-21T11:47:07","modified_gmt":"2023-12-21T04:47:07","slug":"skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus","status":"publish","type":"post","link":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/","title":{"rendered":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566 \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 AI \u0e41\u0e25\u0e30 Longevity \u0e44\u0e14\u0e49\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21!"},"content":{"rendered":"<p><a href=\"http:\/\/www.skooldio.com\"><strong>Skooldio<\/strong><\/a> \u0e41\u0e25\u0e30 <a href=\"http:\/\/www.degree.plus\"><strong>Degree Plus<\/strong><\/a> \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d <strong>LEARN Corporation<\/strong> \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional &amp; Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21 AI \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21 Longevity &amp; Well-being \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e43\u0e19\u0e1b\u0e35 2566 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21\u0e08\u0e32\u0e01\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e2d\u0e14\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c AI \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e01\u0e31\u0e1a\u0e43\u0e19\u0e2a\u0e32\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e41\u0e2a <strong>Lifelong Learning<\/strong> \u0e43\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21<\/p>\n<p>\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e27\u0e41\u0e25\u0e30\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2a\u0e39\u0e07 \u0e20\u0e32\u0e04\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e42\u0e25\u0e01\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e49\u0e32\u0e21\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 Skooldio \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e15\u0e25\u0e32\u0e14\u0e1b\u0e35 2566 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30 AI \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 Generative AI and ChatGPT \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30 AI \u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 AI \u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21 \u0e40\u0e0a\u0e48\u0e19 Data Analytics, SEO Marketing \u0e41\u0e25\u0e30 Graphic Design \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d Skooldio \u0e2d\u0e22\u0e48\u0e32\u0e07 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 Upskill &amp; Reskill \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u2018Decentralized Finance and Blockchain\u2019 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a DeFi \u0e41\u0e25\u0e30 Blockchain, \u2018VELA\u2019 (Vitality Enhancement &amp; Longevity Academy) \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 Medical Hub \u0e41\u0e25\u0e30\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e01\u0e31\u0e1a \u2018Care D+\u2019 \u0e2b\u0e23\u0e37\u0e2d \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e41\u0e25\u0e30\u0e08\u0e38\u0e2c\u0e32\u0e2f \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e08\u0e34\u0e15\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e41\u0e25\u0e30\u0e0d\u0e32\u0e15\u0e34\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e01\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21 \u0e21\u0e35\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e23\u0e48\u0e27\u0e21\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e27\u0e48\u0e32 10,000 \u0e04\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e35 2566<\/p>\n<p>\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e01\u0e23\u0e30\u0e41\u0e2a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e39\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e01 Skooldio \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e1d\u0e31\u0e48\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e2f \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e08\u0e36\u0e07\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e48\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e04\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21 AI \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30 Longevity &amp; Well-being \u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 Lifelong Learning \u0e43\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e31\u0e19\u0e43\u0e01\u0e25\u0e49 \u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23 Synergy \u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Skooldio \u0e15\u0e32\u0e21\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e02\u0e2d\u0e07 LEARN Corporation \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e08\u0e38\u0e14\u0e41\u0e02\u0e47\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e25\u0e49\u0e27\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e17\u0e22\u0e17\u0e31\u0e14\u0e40\u0e17\u0e35\u0e22\u0e21\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e15\u0e48\u0e2d\u0e44\u0e1b\u201d<\/p>\n<p>\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e32\u0e01 <strong>Skooldio<\/strong> \u0e41\u0e25\u0e30 <strong>Degree Plus<\/strong> \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"http:\/\/www.skooldio.com\">www.skooldio.com<\/a> \u0e41\u0e25\u0e30 <a href=\"http:\/\/www.degree.plus\">www.degree.plus<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional &amp; Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21 AI \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e19 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":38365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[64,249,251,252,253,254],"class_list":["post-38364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_post","tag-learn-corporation","tag-lifelong-learning-edtech","tag-ignite-by-ondemand","tag-edusmith","tag-tcaster","tag-medical-career-school"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566<\/title>\n<meta name=\"description\" content=\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional &amp; Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566\" \/>\n<meta property=\"og:description\" content=\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional &amp; Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/\" \/>\n<meta property=\"og:site_name\" content=\"LEARN Corporation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/LEARNCorporation\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-20T07:21:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T04:47:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.learn.co.th\/wp-content\/uploads\/2023\/12\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/person\\\/244e89517660d41e1603149fe153956f\"},\"headline\":\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566 \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 AI \u0e41\u0e25\u0e30 Longevity \u0e44\u0e14\u0e49\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21!\",\"datePublished\":\"2023-12-20T07:21:48+00:00\",\"dateModified\":\"2023-12-21T04:47:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/\"},\"wordCount\":77,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg\",\"keywords\":[\"LEARN CORPORATION\",\"Lifelong Learning EdTech\",\"Ignite by OnDemand\",\"EduSmith\",\"TCASter\",\"Medical Career School\"],\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/\",\"name\":\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg\",\"datePublished\":\"2023-12-20T07:21:48+00:00\",\"dateModified\":\"2023-12-21T04:47:07+00:00\",\"description\":\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional & Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg\",\"contentUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/news_post\\\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566 \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 AI \u0e41\u0e25\u0e30 Longevity \u0e44\u0e14\u0e49\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/\",\"name\":\"LEARN Corporation\",\"description\":\"Lifelong Learning EdTech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#organization\"},\"alternateName\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#organization\",\"name\":\"LEARN Corporation\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Screenshot-2568-01-23-at-15.58.51.png\",\"contentUrl\":\"https:\\\/\\\/www.learn.co.th\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Screenshot-2568-01-23-at-15.58.51.png\",\"width\":2122,\"height\":1240,\"caption\":\"LEARN Corporation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/LEARNCorporation\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.learn.co.th\\\/en\\\/#\\\/schema\\\/person\\\/244e89517660d41e1603149fe153956f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566","description":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional & Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/","og_locale":"en_US","og_type":"article","og_title":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566","og_description":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional & Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio","og_url":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/","og_site_name":"LEARN Corporation","article_publisher":"https:\/\/web.facebook.com\/LEARNCorporation\/","article_published_time":"2023-12-20T07:21:48+00:00","article_modified_time":"2023-12-21T04:47:07+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2023\/12\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#article","isPartOf":{"@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/"},"author":{"name":"admin","@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/person\/244e89517660d41e1603149fe153956f"},"headline":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566 \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 AI \u0e41\u0e25\u0e30 Longevity \u0e44\u0e14\u0e49\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21!","datePublished":"2023-12-20T07:21:48+00:00","dateModified":"2023-12-21T04:47:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/"},"wordCount":77,"commentCount":0,"publisher":{"@id":"https:\/\/www.learn.co.th\/en\/#organization"},"image":{"@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2023\/12\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg","keywords":["LEARN CORPORATION","Lifelong Learning EdTech","Ignite by OnDemand","EduSmith","TCASter","Medical Career School"],"articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/","url":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/","name":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566","isPartOf":{"@id":"https:\/\/www.learn.co.th\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#primaryimage"},"image":{"@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2023\/12\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg","datePublished":"2023-12-20T07:21:48+00:00","dateModified":"2023-12-21T04:47:07+00:00","description":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d LEARN Corporation \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d Professional & Skills \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 Skooldio","breadcrumb":{"@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#primaryimage","url":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2023\/12\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg","contentUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2023\/12\/\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c-\u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25-\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23-\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17-\u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d-\u0e08\u0e33\u0e01\u0e31\u0e14.jpg","width":2048,"height":1365,"caption":"\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e34\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e38\u0e25 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e04\u0e39\u0e25\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14"},{"@type":"BreadcrumbList","@id":"https:\/\/www.learn.co.th\/en\/news_post\/skooldio-%e0%b9%81%e0%b8%a5%e0%b8%b0-degree-plus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.learn.co.th\/en\/"},{"@type":"ListItem","position":2,"name":"Skooldio \u0e41\u0e25\u0e30 Degree Plus \u0e08\u0e31\u0e1a\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c\u0e1b\u0e35 2566 \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 AI \u0e41\u0e25\u0e30 Longevity \u0e44\u0e14\u0e49\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e21!"}]},{"@type":"WebSite","@id":"https:\/\/www.learn.co.th\/en\/#website","url":"https:\/\/www.learn.co.th\/en\/","name":"LEARN Corporation","description":"Lifelong Learning EdTech","publisher":{"@id":"https:\/\/www.learn.co.th\/en\/#organization"},"alternateName":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.learn.co.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.learn.co.th\/en\/#organization","name":"LEARN Corporation","url":"https:\/\/www.learn.co.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2025\/01\/Screenshot-2568-01-23-at-15.58.51.png","contentUrl":"https:\/\/www.learn.co.th\/wp-content\/uploads\/2025\/01\/Screenshot-2568-01-23-at-15.58.51.png","width":2122,"height":1240,"caption":"LEARN Corporation"},"image":{"@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/LEARNCorporation\/"]},{"@type":"Person","@id":"https:\/\/www.learn.co.th\/en\/#\/schema\/person\/244e89517660d41e1603149fe153956f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c9bc69f50a4ab162b5100309d797a7c66367fc43a52db2faa2c36569224283b?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts\/38364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/comments?post=38364"}],"version-history":[{"count":5,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts\/38364\/revisions"}],"predecessor-version":[{"id":38371,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/posts\/38364\/revisions\/38371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/media\/38365"}],"wp:attachment":[{"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/media?parent=38364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/categories?post=38364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.learn.co.th\/en\/wp-json\/wp\/v2\/tags?post=38364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}